{"id":25,"count":214,"description":"Weekly updates in three charts","link":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/","name":"Investment insights","slug":"investment-insights","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Investment insights | Syfe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investment insights Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/\" \/>\n<meta property=\"og:site_name\" content=\"Connect\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/\",\"url\":\"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/\",\"name\":\"Investment insights | Syfe\",\"isPartOf\":{\"@id\":\"https:\/\/www.syfe.com\/magazine\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.syfe.com\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investment insights\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.syfe.com\/magazine\/#website\",\"url\":\"https:\/\/www.syfe.com\/magazine\/\",\"name\":\"Connect\",\"description\":\"Helping you take charge of your financial future\",\"publisher\":{\"@id\":\"https:\/\/www.syfe.com\/magazine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.syfe.com\/magazine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.syfe.com\/magazine\/#organization\",\"name\":\"Syfe Pte Ltd\",\"url\":\"https:\/\/www.syfe.com\/magazine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.syfe.com\/magazine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.syfe.com\/magazine\/wp-content\/uploads\/2019\/05\/logo_black.png\",\"contentUrl\":\"https:\/\/www.syfe.com\/magazine\/wp-content\/uploads\/2019\/05\/logo_black.png\",\"width\":550,\"height\":240,\"caption\":\"Syfe Pte Ltd\"},\"image\":{\"@id\":\"https:\/\/www.syfe.com\/magazine\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Investment insights | Syfe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/","og_locale":"en_US","og_type":"article","og_title":"Investment insights Archives","og_url":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/","og_site_name":"Connect","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/","url":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/","name":"Investment insights | Syfe","isPartOf":{"@id":"https:\/\/www.syfe.com\/magazine\/#website"},"breadcrumb":{"@id":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.syfe.com\/magazine\/category\/investment-insights\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.syfe.com\/magazine\/"},{"@type":"ListItem","position":2,"name":"Investment insights"}]},{"@type":"WebSite","@id":"https:\/\/www.syfe.com\/magazine\/#website","url":"https:\/\/www.syfe.com\/magazine\/","name":"Connect","description":"Helping you take charge of your financial future","publisher":{"@id":"https:\/\/www.syfe.com\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.syfe.com\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.syfe.com\/magazine\/#organization","name":"Syfe Pte Ltd","url":"https:\/\/www.syfe.com\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.syfe.com\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/www.syfe.com\/magazine\/wp-content\/uploads\/2019\/05\/logo_black.png","contentUrl":"https:\/\/www.syfe.com\/magazine\/wp-content\/uploads\/2019\/05\/logo_black.png","width":550,"height":240,"caption":"Syfe Pte Ltd"},"image":{"@id":"https:\/\/www.syfe.com\/magazine\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.syfe.com\/magazine\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.syfe.com\/magazine\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.syfe.com\/magazine\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.syfe.com\/magazine\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}